{"id":37070,"date":"2025-02-27T13:57:12","date_gmt":"2025-02-27T16:57:12","guid":{"rendered":"https:\/\/www.protec.com.br\/?post_type=product&#038;p=37070"},"modified":"2026-02-13T11:59:36","modified_gmt":"2026-02-13T14:59:36","slug":"conector-reto-amostragem-sistema-vafo","status":"publish","type":"product","link":"https:\/\/www.protec.com.br\/es\/producto\/conector-reto-amostragem-sistema-vafo\/","title":{"rendered":"CONECTOR RETO AMOSTRAGEM SISTEMA VAFO"},"content":{"rendered":"<p>Os Conectores de Alum\u00ednio Protec s\u00e3o dispositivos constru\u00eddos em alum\u00ednio (AL) com acabamento anodizado, sa\u00eddas com conex\u00f5es do tipo luer em alum\u00ednio anodizado e revestimento interno em silicone, dispon\u00edveis em v\u00e1rios modelos, a fim de se adequar a diversos procedimentos m\u00e9dico-hospitalares.<\/p>\n<p>As seguintes op\u00e7\u00f5es de conex\u00f5es Luer est\u00e3o previstas para estes conectores de alum\u00ednio:<\/p>\n<ul>\n<li>Conex\u00e3o Luer Macho<\/li>\n<li>Conex\u00e3o Luer Femea<\/li>\n<\/ul>\n<p>Estes conectores de alum\u00ednio foram desenvolvidos para utilizar em conjunto com circuitos de ventila\u00e7\u00e3o e anestesia e circuitos interligados a controladores de administra\u00e7\u00e3o de \u00f3xido n\u00edtrico inalat\u00f3rio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os Conectores de Alum\u00ednio Protec s\u00e3o dispositivos constru\u00eddos em alum\u00ednio (AL) com acabamento anodizado, sa\u00eddas com conex\u00f5es do tipo luer em alum\u00ednio anodizado e revestimento interno em silicone, dispon\u00edveis em v\u00e1rios modelos, a fim de se adequar a diversos procedimentos m\u00e9dico-hospitalares.<\/p>\n<p>As seguintes op\u00e7\u00f5es de conex\u00f5es Luer est\u00e3o previstas para estes conectores de alum\u00ednio:<\/p>\n<ul>\n<li>Conex\u00e3o Luer Macho<\/li>\n<li>Conex\u00e3o Luer Femea<\/li>\n<\/ul>\n<p>Estes conectores de alum\u00ednio foram desenvolvidos para utilizar em conjunto com circuitos de ventila\u00e7\u00e3o e anestesia e circuitos interligados a controladores de administra\u00e7\u00e3o de \u00f3xido n\u00edtrico inalat\u00f3rio.<\/p>","protected":false},"featured_media":37071,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[21,545],"product_tag":[],"class_list":{"0":"post-37070","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-menu-anestesia","7":"product_cat-conector-aluminio","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product\/37070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product\/37070\/revisions"}],"predecessor-version":[{"id":41777,"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product\/37070\/revisions\/41777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/media\/37071"}],"wp:attachment":[{"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/media?parent=37070"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product_brand?post=37070"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product_cat?post=37070"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.protec.com.br\/es\/wp-json\/wp\/v2\/product_tag?post=37070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}