{"id":258,"count":15,"description":"Conjunto de pe\u00e7as originais projetado para manuten\u00e7\u00e3o e substitui\u00e7\u00e3o no posto parede, garantindo seguran\u00e7a, durabilidade e pleno funcionamento da rede de gases.","link":"https:\/\/www.protec.com.br\/en\/product-category\/menu-gasoterapia\/posto-parede-reposicao\/","name":"Kits de Reposi\u00e7\u00e3o Posto Parede","slug":"posto-parede-reposicao","taxonomy":"product_cat","parent":24,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat\/24"}],"wp:post_type":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product?product_cat=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}