{"id":5181,"date":"2022-06-24T09:29:43","date_gmt":"2022-06-24T12:29:43","guid":{"rendered":"https:\/\/www.protec.com.br\/?post_type=product&#038;p=5181"},"modified":"2026-02-12T09:46:20","modified_gmt":"2026-02-12T12:46:20","slug":"tomada-tripla-com-valvula-o2","status":"publish","type":"product","link":"https:\/\/www.protec.com.br\/en\/product\/tomada-tripla-com-valvula-o2\/","title":{"rendered":"TOMADA TRIPLA COM VALV\u00daLA O2"},"content":{"rendered":"<p>As tomadas duplas e triplas tem como fun\u00e7\u00e3o principal multiplicar os pontos de gases medicinais dando maior autonomia em locais onde os pontos de gases medicinais s\u00e3o escassos.<\/p>\n<p>As Tomadas Duplas e triplas da marca Protec possuem v\u00e1lvula de impacto para bloqueio do g\u00e1s medicinal quando o bico auxiliar n\u00e3o esta em uso. Indicada para uso nos pontos de gases medicinais, reguladores de press\u00e3o (V\u00e1lvulas de cilindros, v\u00e1lvulas reguladoras de press\u00e3o), neste caso a sa\u00edda ser\u00e1 igual \u00e0 press\u00e3o ajustada na v\u00e1lvula redutora de press\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>As tomadas duplas e triplas s\u00e3o indicadas para uso em postos medicinais, reguladores de press\u00e3o de oxig\u00eanio, ar comprimido, v\u00e1cuo e \u00f3xido nitroso. Sua finalidade \u00e9 multiplicar as sa\u00eddas de gases.<\/p>\n<p><strong>RMS:<\/strong> 80435149004<\/p>","protected":false},"featured_media":28870,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[24,267],"product_tag":[144,141,143,145,133],"class_list":{"0":"post-5181","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-menu-gasoterapia","7":"product_cat-tomadas-duplas-e-triplas","8":"product_tag-dupla","9":"product_tag-impacto","10":"product_tag-tomada","11":"product_tag-tripla","12":"product_tag-valvula","14":"first","15":"instock","16":"virtual","17":"taxable","18":"purchasable","19":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/5181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/5181\/revisions"}],"predecessor-version":[{"id":42721,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/5181\/revisions\/42721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media\/28870"}],"wp:attachment":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media?parent=5181"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=5181"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=5181"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=5181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}