{"id":31680,"date":"2024-07-19T09:48:40","date_gmt":"2024-07-19T12:48:40","guid":{"rendered":"https:\/\/beta.alcinfotech.com.br\/?post_type=product&#038;p=31680"},"modified":"2026-02-13T11:24:42","modified_gmt":"2026-02-13T14:24:42","slug":"kit-interno-valvula-peep-25a10","status":"publish","type":"product","link":"https:\/\/www.protec.com.br\/en\/product\/kit-interno-valvula-peep-25a10\/","title":{"rendered":"KIT INTERNO V\u00c1LVULA PEEP 2,5 A 10"},"content":{"rendered":"<p>A v\u00e1lvula PEEP (Press\u00e3o Positiva Expirat\u00f3ria Final) em policarbonato (PC) e mola com carga ajust\u00e1vel de 2.5 a 10cm H2O e a 20cm H2O. Indicada para utiliza\u00e7\u00e3o em sistema CPAP\/ EPAP ou ressuscitador Manual, com a finalidade de manter uma press\u00e3o positiva pr\u00e9-determinada ao final da expira\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RMS:<\/strong> 80435140026<\/p>","protected":false},"excerpt":{"rendered":"<p>A v\u00e1lvula PEEP (Press\u00e3o Positiva Expirat\u00f3ria Final) em policarbonato (PC) e mola com carga ajust\u00e1vel de 2.5 a 10cm H2O e a 20cm H2O. Indicada para utiliza\u00e7\u00e3o em sistema CPAP\/ EPAP ou ressuscitador Manual, com a finalidade de manter uma press\u00e3o positiva pr\u00e9-determinada ao final da expira\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RMS:<\/strong> 80435140026<\/p>","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[477],"product_tag":[],"class_list":{"0":"post-31680","1":"product","2":"type-product","3":"status-publish","5":"product_cat-valvula-peep","7":"first","8":"instock","9":"taxable","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31680\/revisions"}],"predecessor-version":[{"id":42655,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31680\/revisions\/42655"}],"wp:attachment":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media?parent=31680"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=31680"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=31680"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=31680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}