{"id":31559,"date":"2024-07-18T10:36:30","date_gmt":"2024-07-18T13:36:30","guid":{"rendered":"https:\/\/beta.alcinfotech.com.br\/?post_type=product&#038;p=31559"},"modified":"2026-02-12T09:43:51","modified_gmt":"2026-02-12T12:43:51","slug":"tomada-t-o2-argonio","status":"publish","type":"product","link":"https:\/\/www.protec.com.br\/en\/product\/tomada-t-o2-argonio\/","title":{"rendered":"TOMADA T O2 \/ ARG\u00d4NIO"},"content":{"rendered":"<p>As tomadas duplas e triplas tem como fun\u00e7\u00e3o principal multiplicar os pontos de gases medicinais dando maior autonomia em locais onde os pontos de gases medicinais s\u00e3o escassos.<\/p>\n<p>As Tomadas Duplas e triplas da marca Protec possuem v\u00e1lvula de impacto para bloqueio do g\u00e1s medicinal quando o bico auxiliar n\u00e3o esta em uso. Indicada para uso nos pontos de gases medicinais, reguladores de press\u00e3o (V\u00e1lvulas de cilindros, v\u00e1lvulas reguladoras de press\u00e3o), neste caso a sa\u00edda ser\u00e1 igual \u00e0 press\u00e3o ajustada na v\u00e1lvula redutora de press\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>As tomadas duplas e triplas tem como fun\u00e7\u00e3o principal multiplicar os pontos de gases medicinais dando maior autonomia em locais onde os pontos de gases medicinais s\u00e3o escassos.<\/p>\n<p>As Tomadas Duplas e triplas da marca Protec possuem v\u00e1lvula de impacto para bloqueio do g\u00e1s medicinal quando o bico auxiliar n\u00e3o esta em uso. Indicada para uso nos pontos de gases medicinais, reguladores de press\u00e3o (V\u00e1lvulas de cilindros, v\u00e1lvulas reguladoras de press\u00e3o), neste caso a sa\u00edda ser\u00e1 igual \u00e0 press\u00e3o ajustada na v\u00e1lvula redutora de press\u00e3o.<\/p>","protected":false},"featured_media":31560,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[24,267],"product_tag":[510,509],"class_list":{"0":"post-31559","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-menu-gasoterapia","7":"product_cat-tomadas-duplas-e-triplas","8":"product_tag-o2-e-argonio","9":"product_tag-tomada-t","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31559\/revisions"}],"predecessor-version":[{"id":42718,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31559\/revisions\/42718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media\/31560"}],"wp:attachment":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media?parent=31559"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=31559"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=31559"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=31559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}