{"id":31323,"date":"2024-07-15T09:37:08","date_gmt":"2024-07-15T12:37:08","guid":{"rendered":"https:\/\/beta.alcinfotech.com.br\/?post_type=product&#038;p=31323"},"modified":"2026-02-13T16:51:24","modified_gmt":"2026-02-13T19:51:24","slug":"circuito-anestesia-baraka-undir-latex-free-2-litro-sem-mascara-2","status":"publish","type":"product","link":"https:\/\/www.protec.com.br\/en\/product\/circuito-anestesia-baraka-undir-latex-free-2-litro-sem-mascara-2\/","title":{"rendered":"CIRCUITO DE ANESTESIA BARAKA L\u00c1TEX FREE UNIDIRECIONAL 2L SEM M\u00c1SCARA"},"content":{"rendered":"<p>Os Circuitos de Anestesia Baraka fabricado pela Protec possui dois modelos (com v\u00e1lvula unidirecional ou traqueia em silicone) e diversas configura\u00e7\u00f5es com diferentes tamanhos de m\u00e1scaras faciais e bal\u00f5es respirat\u00f3rios. Todos os modelos possuem em sua composi\u00e7\u00e3o o bal\u00e3o respirat\u00f3rio l\u00e1tex free.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RMS: 80435140046<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Os Circuitos de Anestesia Baraka fabricado pela Protec possui dois modelos (com v\u00e1lvula unidirecional ou traqueia em silicone) e diversas configura\u00e7\u00f5es com diferentes tamanhos de m\u00e1scaras faciais e bal\u00f5es respirat\u00f3rios. Todos os modelos possuem em sua composi\u00e7\u00e3o o bal\u00e3o respirat\u00f3rio l\u00e1tex free.<\/p>\n<p><strong>RMS: 80435140046<br \/>\n<\/strong><\/p>\n<ul>\n<li>Composto por bal\u00e3o l\u00e1tex free 1\/2, 1, 2, 3 ou 5 litros;<\/li>\n<li>1 conector &#8220;T&#8221; ayres com entrada de g\u00e1s na v\u00e1lvula superior;<\/li>\n<li>1 v\u00e1lvula superior<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>","protected":false},"featured_media":36163,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[18],"product_tag":[],"class_list":{"0":"post-31323","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sem-categoria","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31323\/revisions"}],"predecessor-version":[{"id":41692,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/31323\/revisions\/41692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media\/36163"}],"wp:attachment":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media?parent=31323"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=31323"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=31323"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=31323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}