{"id":105,"date":"2019-12-18T11:18:11","date_gmt":"2019-12-18T14:18:11","guid":{"rendered":"http:\/\/projeto.online\/protec\/?post_type=product&#038;p=105"},"modified":"2026-02-19T17:02:14","modified_gmt":"2026-02-19T20:02:14","slug":"monitor-multiparametrico-rd12-pre-configurados-6-parametros","status":"publish","type":"product","link":"https:\/\/www.protec.com.br\/en\/product\/monitor-multiparametrico-rd12-pre-configurados-6-parametros\/","title":{"rendered":"MONITOR MULTIPARAM\u00c9TRICO PR\u00c9-CONFIGURADO RD12 6 PAR\u00c2METROS"},"content":{"rendered":"<div>Desenvolvido com tecnologia de ponta 100% nacional os monitores multiparam\u00e9tricos pr\u00e9 configurados RD15\u00a0 e RD12 s\u00e3o os mais novos integrantes da linha M Series. Com design moderno e inovador, possuem tela touch screen 15\u201d \/ 12\u201d com excelente resolu\u00e7\u00e3o, o que possibilita visualiza\u00e7\u00e3o de todas as curvas e tra\u00e7ados de forma ampla.<\/div>\n<div>Leves e compactos, se adaptam aos mais diversos ambientes, que v\u00e3o desde a triagem at\u00e9 unidades de terapia intensiva de alta complexidade. A grande variedade de par\u00e2metros possibilita avalia\u00e7\u00e3o\u00a0completa de pacientes.<\/div>\n<div><\/div>\n<div><strong>RMS<\/strong>: 80435140063<\/div>","protected":false},"excerpt":{"rendered":"<p>Os monitores multiparam\u00e9tricos pr\u00e9-configurados RD15 e RD12, foram desenvolvidos para monitorizar um conjunto fixo de par\u00e2metros, de acordo com os m\u00f3dulos internos instalados: ECG, Oximetria, Press\u00e3o n\u00e3o invasiva, Respira\u00e7\u00e3o e Temperatura.<br \/>\n<strong>M\u00f3dulos internos opcionais: <\/strong>Oximetria Nellcor Oximax, Press\u00e3o invasiva, D\u00e9bito card\u00edaco e Capnografia.<\/p>\n<p><strong>RMS<\/strong>: 80435140063<\/p>","protected":false},"featured_media":33771,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[26,299],"product_tag":[],"class_list":{"0":"post-105","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-menu-monitores","7":"product_cat-monitores-multiparametricos","9":"first","10":"instock","11":"virtual","12":"taxable","13":"purchasable","14":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/105\/revisions"}],"predecessor-version":[{"id":33772,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product\/105\/revisions\/33772"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media\/33771"}],"wp:attachment":[{"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/media?parent=105"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_brand?post=105"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_cat?post=105"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.protec.com.br\/en\/wp-json\/wp\/v2\/product_tag?post=105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}